{"id":14,"date":"2023-03-29T10:19:37","date_gmt":"2023-03-29T08:19:37","guid":{"rendered":"https:\/\/paypymes.es\/blog\/potenti-fames-amet-aliquam-vitae-vivamus-venenatis-nisl-imperdiet-pharetra-nulla\/"},"modified":"2024-03-26T16:56:19","modified_gmt":"2024-03-26T15:56:19","slug":"como-saber-si-estoy-lista-morosos","status":"publish","type":"post","link":"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/","title":{"rendered":"C\u00f3mo saber si estoy en una lista de morosos"},"content":{"rendered":"<p><b>\u00bfC\u00f3mo saber si estoy en una lista de morosos?<\/b><span style=\"font-weight: 400;\"> Esa es una pregunta que se hacen muchas empresas con deudas y facturas impagadas. Aunque pueda sonar complicado, es algo m\u00e1s sencillo de entender de lo que parece.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es importante consultar una lista de morosos para evitar cualquier impago en el caso de que tengamos una empresa o seamos aut\u00f3nomos. Recurrir por ejemplo a la lista de morosos ASNEF nos puede evitar muchos disgustos en la econom\u00eda de nuestra empresa, y es una forma de prevenir casos en los que un cliente se niega a pagar sus facturas o simplemente se declara insolvente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En nuestro art\u00edculo, vamos a explicar <\/span><b>qu\u00e9 son estas listas<\/b><span style=\"font-weight: 400;\">, <\/span><b>c\u00f3mo saber si estamos en ellas<\/b><span style=\"font-weight: 400;\"> y <\/span><b>c\u00f3mo podemos dejar de estar en las mismas.<\/b><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_73 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#Que_es_una_lista_de_morosos\" title=\"Qu\u00e9 es una lista de morosos\u00a0\">Qu\u00e9 es una lista de morosos\u00a0<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#%C2%BFDonde_consultar_la_lista_de_morosos\" title=\"\u00bfD\u00f3nde consultar la lista de morosos?\u00a0\">\u00bfD\u00f3nde consultar la lista de morosos?\u00a0<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#%C2%BFComo_saber_si_estoy_en_la_lista_de_morosos\" title=\"\u00bfC\u00f3mo saber si estoy en la lista de morosos?\u00a0\">\u00bfC\u00f3mo saber si estoy en la lista de morosos?\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#%C2%BFPor_que_es_importante_conocer_la_lista_de_morosos_en_Espana\" title=\"\u00bfPor qu\u00e9 es importante conocer la lista de morosos en Espa\u00f1a?\">\u00bfPor qu\u00e9 es importante conocer la lista de morosos en Espa\u00f1a?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#Como_funcionan_las_listas_de_morosos\" title=\"C\u00f3mo funcionan las listas de morosos\u00a0\">C\u00f3mo funcionan las listas de morosos\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#Cuanto_tiempo_puedes_permanecer_en_un_registro_de_morosos\" title=\"Cu\u00e1nto tiempo puedes permanecer en un registro de morosos\u00a0\">Cu\u00e1nto tiempo puedes permanecer en un registro de morosos\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#Como_salir_de_una_lista_de_morosos\" title=\"C\u00f3mo salir de una lista de morosos\u00a0\">C\u00f3mo salir de una lista de morosos\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/#%C2%BFComo_puede_ayudarte_PayPymes_con_los_morosos\" title=\"\u00bfC\u00f3mo puede ayudarte PayPymes con los morosos?\u00a0\">\u00bfC\u00f3mo puede ayudarte PayPymes con los morosos?\u00a0<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Que_es_una_lista_de_morosos\"><\/span><b>Qu\u00e9 es una lista de morosos\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Una lista de morosos es un <\/span><b>registro <\/b><span style=\"font-weight: 400;\">donde se recogen las<\/span><b> personas que no han cumplido puntualmente con sus obligaciones de pago<\/b><span style=\"font-weight: 400;\">. Por tanto,<\/span><b> figurar en uno de estos ficheros puede ser un problema<\/b><span style=\"font-weight: 400;\"> a la hora de acceder a cr\u00e9dito o a determinados servicios. Por eso mismo, consultar la lista de morosos e informarte acerca de ello puede sacarte de m\u00e1s de un apuro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las listas de morosos suelen ser<\/span><b> consultadas por entidades financieras <\/b><span style=\"font-weight: 400;\">antes de conceder un cr\u00e9dito o por la compa\u00f1\u00eda de telefon\u00eda antes de firmar un contrato. Tambi\u00e9n las consultan<\/span> <span style=\"font-weight: 400;\">empresas<\/span><b> para conocer la solvencia de un posible cliente.<\/b><span style=\"font-weight: 400;\"> En definitiva, es una <\/span><b>herramienta que proporciona seguridad financiera<\/b><span style=\"font-weight: 400;\"> antes de realizar una transacci\u00f3n econ\u00f3mica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por tanto, estar dentro de una lista de morosos puede suponer muchos inconvenientes. Con los ejemplos anteriores, <\/span><b>a una persona o empresa que est\u00e9 en el registro se le podr\u00eda denegar un pr\u00e9stamo, el servicio telef\u00f3nico o un lucrativo<\/b><span style=\"font-weight: 400;\"> contrato. Ese es el motivo por el que la inclusi\u00f3n en estos registros suele emplearse como amenaza para el cobro de deudas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, cualquier empresa puede consultar una <\/span><b>lista de morosos particulares<\/b><span style=\"font-weight: 400;\"> para <\/span><b>comprobar que el cliente es solvente<\/b><span style=\"font-weight: 400;\">, por lo que es tambi\u00e9n un m\u00e9todo de prevenci\u00f3n de impagos y de garantizar que obtendremos una remuneraci\u00f3n por nuestros servicios.\u00a0<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFDonde_consultar_la_lista_de_morosos\"><\/span><b>\u00bfD\u00f3nde consultar la lista de morosos?\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Las <\/span><b>listas de morosos en Espa\u00f1a m\u00e1s usadas<\/b><span style=\"font-weight: 400;\"> son:<\/span><\/p>\n<ul>\n<li><b>ASNEF.<\/b><span style=\"font-weight: 400;\"> La Asociaci\u00f3n Nacional de Entidades Financieras es el principal registro del Estado. Se puede entrar por cualquier importe, ya que no hay m\u00ednimo para figurar en su fichero.<\/span><\/li>\n<li><b>RAI.<\/b><span style=\"font-weight: 400;\"> El Registro de Aceptaciones Impagadas recoge impagos iguales o superiores a 300 \u20ac.<\/span><\/li>\n<li><b>CIRBE La Central de Informaci\u00f3n de Riesgos.<\/b><span style=\"font-weight: 400;\"> Es una base de datos que recoge la informaci\u00f3n de los pr\u00e9stamos, cr\u00e9ditos (riesgo directo), avales y garant\u00edas (riesgo indirecto) que cada entidad de cr\u00e9dito mantiene con sus clientes.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Cada uno de ellos requiere una <\/span><b>serie de documentaci\u00f3n para poder acceder a sus bases de datos y consultar si formamos parte de ellas<\/b><span style=\"font-weight: 400;\">. En el caso de ASNEF, solicitan datos personales como el DNI o CIF, la direcci\u00f3n postal, as\u00ed como la documentaci\u00f3n referente a la deuda. Se puede acceder a CIRBE con el DNI y rellenando un formulario. Por su parte, para conocer si se est\u00e1 dentro de un listado RAI, con el CIF y completando un formulario web de solicitud, ser\u00e1 suficiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una vez enviados los datos requeridos y solicitado el acceso, en el<\/span><b> plazo de un mes<\/b><span style=\"font-weight: 400;\"> los usuarios pueden recoger la informaci\u00f3n de forma presencial en alguno de estos organismos, o bien solicitar su recepci\u00f3n en su propio domicilio por correo certificado, para conocer si sus datos est\u00e1n inscritos dentro del listado de morosos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es importante recordar que, para que alguien aparezca en una de estas listas no basta con deber dinero. La <\/span><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2018-16673\" rel=\"nofollow noopener\" target=\"_blank\"><span style=\"font-weight: 400;\">Ley Org\u00e1nica 3\/2018 de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales<\/span><\/a><span style=\"font-weight: 400;\"> establece que la deuda debe ser demostrable y exigible, y haber vencido el plazo de pago; adem\u00e1s, el acreedor debe informar antes al deudor de que puede ser incluido en una lista de morosos, notific\u00e1ndoselo debidamente.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_saber_si_estoy_en_la_lista_de_morosos\"><\/span><b>\u00bfC\u00f3mo saber si estoy en la lista de morosos?\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A veces, por errores en los datos de contacto del deudor, la notificaci\u00f3n nunca llega y se dan casos en los que el deudor no sabe que tiene una deuda pendiente, o incluso que su nombre aparece en una <\/span><b>p\u00e1gina de deudores morosos en Internet<\/b><span style=\"font-weight: 400;\">. Entonces, <\/span><b>\u00bfc\u00f3mo saber si estoy en la lista de morosos?<\/b><span style=\"font-weight: 400;\"> Es posible contactar por Internet con alguna de las entidades arriba mencionadas, y ver la lista de morosos en sus registros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada una requiere una documentaci\u00f3n distinta, pero lo normal es que baste con el <\/span><b>DNI <\/b><span style=\"font-weight: 400;\">o <\/span><b>CIF <\/b><span style=\"font-weight: 400;\">y rellenar un formulario, aunque <\/span><b>ASNEF <\/b><span style=\"font-weight: 400;\">por ejemplo pide tambi\u00e9n que se aporte documentaci\u00f3n que <\/span><b>demuestre la deuda.<\/b><span style=\"font-weight: 400;\"> Una vez hecha la solicitud, pasado un mes nos entregar\u00e1n la informaci\u00f3n solicitada y podremos saber si nuestro nombre aparece en sus registros.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_es_importante_conocer_la_lista_de_morosos_en_Espana\"><\/span><b>\u00bfPor qu\u00e9 es importante conocer la lista de morosos en Espa\u00f1a?<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">El impago de recibos y deudas pendientes es un <\/span><b>problema grave que afecta a muchas empresas y aut\u00f3nomos<\/b><span style=\"font-weight: 400;\">, poniendo en riesgo su econom\u00eda e incluso su viabilidad; por ello, conocer <\/span><b>c\u00f3mo consultar una lista de morosos en Espa\u00f1a<\/b><span style=\"font-weight: 400;\"> es fundamental para prevenir cualquier situaci\u00f3n de impago y conocer la solvencia de los clientes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hay que tener en cuenta que figurar en una lista de este tipo trae muchos problemas y obst\u00e1culos para quienes aparecen en ella, ya sea una persona f\u00edsica o una empresa, porque le cierra las puertas a todo tipo de contratos, desde solicitar un cr\u00e9dito hasta simplemente contratar una l\u00ednea telef\u00f3nica. Por tanto, muchas veces el recurso a <\/span><b>advertir al deudor con incluirlo en una lista de morosos <\/b><span style=\"font-weight: 400;\">sirve como acicate para que finalmente acceda a pagar la deuda.<\/span><\/p>\n<p><b>En PayPymes nos preocupamos por ti de reclamar y cobrar las deudas de los morosos<\/b><span style=\"font-weight: 400;\">, para que t\u00fa no tengas que preocuparte por nada m\u00e1s que por seguir adelante con tu negocio y verlo crecer y prosperar. Si quieres m\u00e1s informaci\u00f3n, recuerda que te ofrecemos una <\/span><b>consulta gratuita<\/b><span style=\"font-weight: 400;\"> con un asesor que analizar\u00e1 tu caso y las opciones para recuperar tu dinero, gratis y sin ning\u00fan compromiso. T\u00fa decides si quieres que seamos nosotros quienes reclamemos tu dinero, y<\/span><b> t\u00fa decides c\u00f3mo hacerlo<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_funcionan_las_listas_de_morosos\"><\/span><b>C\u00f3mo funcionan las listas de morosos\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Cuando vence una obligaci\u00f3n, los<\/span><b> servicios de cobros del acreedor instar\u00e1n al deudor moroso a realizar el pago. <\/b><span style=\"font-weight: 400;\">En su aviso le advertir\u00e1n de que, de no realizar el pago, se desplegar\u00e1n determinadas <\/span><b>consecuencias<\/b><span style=\"font-weight: 400;\">. Estas suelen incluir:<\/span><\/p>\n<ul>\n<li aria-level=\"1\"><b>Reclamaciones judiciales<\/b><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\"><b>Cortes de suministros<\/b><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\"><b>Devengo de gastos de recobro y gesti\u00f3n<\/b><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La<\/span><b> inscripci\u00f3n en una lista de morosos<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Se suele otorgar un <\/span><b>plazo de dos o tres meses para resolver la situaci\u00f3n. <\/b><span style=\"font-weight: 400;\">Por supuesto, este plazo depender\u00e1 del acreedor y puede variar en cada situaci\u00f3n. <\/span><b>Si el deudor persiste en su impago, el acreedor informar\u00e1 al registro.<\/b><span style=\"font-weight: 400;\"> Este lo notificar\u00e1 al deudor, que <\/span><b>dispondr\u00e1 de treinta d\u00edas para:<\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">Regularizar su situaci\u00f3n y acreditar que est\u00e1 al corriente de sus obligaciones.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">Impugnar su deuda.<\/span><\/li>\n<\/ul>\n<p><b>En caso contrario, quedar\u00e1 inscrito en la lista de morosos<\/b><span style=\"font-weight: 400;\">, con las dificultades que ello entra\u00f1a.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Cuanto_tiempo_puedes_permanecer_en_un_registro_de_morosos\"><\/span><b>Cu\u00e1nto tiempo puedes permanecer en un registro de morosos\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Cada lista de morosos puede regular la permanencia en su sistema del modo que prefiera.<\/span> <span style=\"font-weight: 400;\">Sin embargo, a tenor de la legislaci\u00f3n de protecci\u00f3n de datos, el<\/span><b> tiempo m\u00e1ximo es de cinco a\u00f1os.<\/b><span style=\"font-weight: 400;\"> En cualquier caso, <\/span><b>el pago de la deuda supone la salida del registro.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, mientras el deudor figure en el registro, siempre que se le deniegue un contrato por estar inscrito en la lista de morosos se le deber\u00e1 informar de este extremo.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_salir_de_una_lista_de_morosos\"><\/span><b>C\u00f3mo salir de una lista de morosos\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si el moroso ha abonado su deuda o no se ha llegado a constituir en mora deber\u00e1 hacer lo posible por salir de la lista de morosos. En ocasiones esta operaci\u00f3n puede ser compleja. Por tanto, se recomienda:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Contar con la asistencia de un abogado bancario o especialista en protecci\u00f3n de datos:<\/b><span style=\"font-weight: 400;\"> Este profesional facilitar\u00e1 los tr\u00e1mites y podr\u00e1 asistir ante los tribunales al deudor.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Entrar en contacto con el gestor del fichero:<\/b><span style=\"font-weight: 400;\"> El acreedor es el encargado de cancelar un asiento, por lo que hay que contactar directamente con el gestor del registro. Hay que acreditar que la deuda nunca existi\u00f3, o ya est\u00e1 saldada.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Denunciar frente a la AEPD:<\/b><span style=\"font-weight: 400;\"> En caso de que la inclusi\u00f3n en el fichero tenga alguna irregularidad, se podr\u00e1 denunciar frente a la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos. <\/span><b>Suele ser lo m\u00e1s efectivo.<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">En cualquier caso, las <\/span><b>v\u00edas de salida de una lista de morosos solo son dos:<\/b><\/p>\n<ul>\n<li aria-level=\"1\"><b>Pagar la deuda.<\/b><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\"><b>Impugnar satisfactoriamente la deuda.<\/b><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_puede_ayudarte_PayPymes_con_los_morosos\"><\/span><b>\u00bfC\u00f3mo puede ayudarte PayPymes con los morosos?\u00a0<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">PayPymes te ofrece la protecci\u00f3n que necesitas para tu negocio con un <\/span><a href=\"https:\/\/www.paypymes.es\/prevencion-impagos\"><b>servicio de prevenci\u00f3n de impagos<\/b><\/a><span style=\"font-weight: 400;\">. Para ello, realizamos an\u00e1lisis e <\/span><b>informes comerciales<\/b><span style=\"font-weight: 400;\"> sobre el estado financiero de tus clientes, y te proporcionamos un <\/span><b>sello f\u00edsico y digital<\/b><span style=\"font-weight: 400;\"> que podr\u00e1s incluir en tus documentos y facturas para que tus clientes sepan que, en caso de impago, <\/span><b>dispones de plena cobertura jur\u00eddica<\/b><span style=\"font-weight: 400;\">. Adem\u00e1s, algunos de estos informes te los ofrecemos <\/span><b>de manera gratuita<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No olvides consultar la lista de morosos para evitar cualquier impago. <\/span><span style=\"font-weight: 400;\">T\u00fa preoc\u00fapate por tu negocio: <\/span><b>de los morosos nos ocupamos nosotros.<\/b><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo saber si estoy en una lista de morosos? Esa es una pregunta que se hacen muchas empresas con deudas y facturas impagadas. Aunque pueda sonar complicado, es algo m\u00e1s sencillo de entender de lo que parece.\u00a0 Es importante consultar una lista de morosos para evitar cualquier impago en el caso de que tengamos una &#8230; <a title=\"C\u00f3mo saber si estoy en una lista de morosos\" class=\"read-more\" href=\"https:\/\/www.paypymes.es\/blog\/como-saber-si-estoy-lista-morosos\/\" aria-label=\"M\u00e1s en C\u00f3mo saber si estoy en una lista de morosos\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":88,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-14","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impagos","category-morosos"],"_links":{"self":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":6,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts\/14\/revisions"}],"predecessor-version":[{"id":175,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts\/14\/revisions\/175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/media\/88"}],"wp:attachment":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/media?parent=14"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/categories?post=14"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/tags?post=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}