{"id":103,"date":"2023-07-14T12:12:16","date_gmt":"2023-07-14T10:12:16","guid":{"rendered":"https:\/\/www.paypymes.es\/blog\/?p=103"},"modified":"2023-07-14T12:44:47","modified_gmt":"2023-07-14T10:44:47","slug":"que-es-un-concurso-de-acreedores","status":"publish","type":"post","link":"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/","title":{"rendered":"\u00bfQu\u00e9 es un concurso de acreedores?"},"content":{"rendered":"<p>Podemos definir el concurso de acreedores como un <strong>procedimiento judicial a disposici\u00f3n de toda empresa o persona f\u00edsica<\/strong> que pasa por una situaci\u00f3n de <strong>insolvencia econ\u00f3mica<\/strong> derivada de la <strong>imposibilidad de atender los pagos<\/strong> a sus acreedores.<\/p>\n<p>El objetivo de este procedimiento, es buscar una soluci\u00f3n a los problemas de falta de liquidez y solvencia de su negocio y que el mayor n\u00famero de acreedores logren cobrar la m\u00e1xima cantidad de dinero posible; as\u00ed como la continuidad del negocio y evitar la quiebra.<\/p>\n<p>Si todav\u00eda no sabes <strong><em>qu\u00e9 es exactamente un concurso de acreedores<\/em><\/strong> y c\u00f3mo se desarrolla, presta atenci\u00f3n a este art\u00edculo; te informamos de todo lo que necesitas saber al respecto.<\/p>\n<p>Este procedimiento legal se encuentra regulado por la <strong><em>Ley Concursal de 2003<\/em><\/strong> y, est\u00e1 dise\u00f1ado para lograr una soluci\u00f3n que permita pagar a los acreedores y garantizar la continuidad de la empresa.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_73 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#%C2%BFQuien_puede_declararse_en_concurso_de_acreedores\" title=\"\u00bfQui\u00e9n puede declararse en concurso de acreedores?\">\u00bfQui\u00e9n puede declararse en concurso de acreedores?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#%C2%BFCuando_y_como_se_declara_el_concurso_de_acreedores\" title=\"\u00bfCu\u00e1ndo y c\u00f3mo se declara el concurso de acreedores?\">\u00bfCu\u00e1ndo y c\u00f3mo se declara el concurso de acreedores?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#%C2%BFComo_saber_si_una_empresa_esta_en_concurso_de_acreedores\" title=\"\u00bfC\u00f3mo saber si una empresa est\u00e1 en concurso de acreedores?\">\u00bfC\u00f3mo saber si una empresa est\u00e1 en concurso de acreedores?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#%C2%BFQue_pasa_si_la_empresa_entra_en_concurso_de_acreedores\" title=\"\u00bfQu\u00e9 pasa si la empresa entra en concurso de acreedores?\">\u00bfQu\u00e9 pasa si la empresa entra en concurso de acreedores?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#Como_empresa_%C2%BFme_pueden_embargar_estando_en_concurso_de_acreedores\" title=\"Como empresa, \u00bfme pueden embargar estando en concurso de acreedores?\">Como empresa, \u00bfme pueden embargar estando en concurso de acreedores?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#Diferencias_entre_concurso_de_acreedores_particulares_y_concurso_de_acreedores_voluntario\" title=\"Diferencias entre concurso de acreedores particulares y concurso de acreedores voluntario\">Diferencias entre concurso de acreedores particulares y concurso de acreedores voluntario<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#Fases_del_concurso_de_acreedores\" title=\"Fases del concurso de acreedores\">Fases del concurso de acreedores<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#Actos_previos\" title=\"Actos previos\">Actos previos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#Fase_comun\" title=\"Fase com\u00fan\">Fase com\u00fan<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#Fase_de_resolucion\" title=\"Fase de resoluci\u00f3n\">Fase de resoluci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#Calificacion_del_concurso\" title=\"Calificaci\u00f3n del concurso\">Calificaci\u00f3n del concurso<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/#%C2%BFCuanto_tiempo_se_tarda_en_resolver_un_concurso_de_acreedores\" title=\"\u00bfCu\u00e1nto tiempo se tarda en resolver un concurso de acreedores?\">\u00bfCu\u00e1nto tiempo se tarda en resolver un concurso de acreedores?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQuien_puede_declararse_en_concurso_de_acreedores\"><\/span>\u00bfQui\u00e9n puede declararse en concurso de acreedores?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Una vez conocemos qu\u00e9 es un concurso de acreedores, debemos saber qui\u00e9n puede declararse como tal. Seg\u00fan el <strong>Texto Refundido de la Ley Concursal<\/strong>, cualquier persona f\u00edsica o jur\u00eddica puede manifestarse en concurso de acreedores.<\/p>\n<p>La declaraci\u00f3n del concurso de acreedores puede hacerse tanto de forma voluntaria por el deudor insolvente como a trav\u00e9s de solicitud por parte de alguno de sus acreedores afectados. Y en \u00faltima instancia por el mediador durante un procedimiento de segunda oportunidad, en los casos en que el deudor incumpla el acuerdo establecido o no se llegue a un acuerdo extrajudicial.<\/p>\n<p>En el primero de los casos, el deudor deber\u00e1 demostrar su estado de insolvencia e incapacidad econ\u00f3mica de hacer frente a sus obligaciones. En el caso, de que sea presentada por el acreedor, este deber\u00e1 incluir en la solicitud, datos como el origen y naturaleza del cr\u00e9dito; el importe, las fechas de adquisici\u00f3n y vencimiento, as\u00ed como la situaci\u00f3n actual de la deuda debidamente soportada. Tambi\u00e9n deber\u00e1 incluir las razones (fundamentadas en la ley) para la solicitud.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuando_y_como_se_declara_el_concurso_de_acreedores\"><\/span>\u00bfCu\u00e1ndo y c\u00f3mo se declara el concurso de acreedores?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Otra de las cuestiones que conviene saber, una vez se tiene claro qu\u00e9 es el concurso de acreedores, es c\u00f3mo y cu\u00e1ndo se ha de resolver. En este sentido, se establece la obligaci\u00f3n de presentar concurso, cuando se conoce la insolvencia de la empresa, actual o inminente.<\/p>\n<p>Un empresario tiene la obligaci\u00f3n de solicitar un procedimiento de concurso de acreedores en el plazo de dos meses, si se comprueba que existe el riesgo de una situaci\u00f3n de insolvencia, ya sea actual o futura. Tambi\u00e9n puede iniciar negociaciones de refinanciaci\u00f3n con sus acreedores, lo que le permitir\u00eda ampliar este periodo. Si no realiza ninguna de las dos opciones, puede conducir a una declaraci\u00f3n de culpabilidad durante el proceso concursal. Por otro lado, sus acreedores tambi\u00e9n pueden realizar la solicitud, en el caso de incumplimiento por parte del deudor.<\/p>\n<p>Una vez presentada la solicitud, si el juez estima acreditada la insolvencia, dictar\u00e1 auto, declarando el concurso que indicar\u00e1 uno de los dos tipos posibles:<\/p>\n<ul>\n<li><strong>Concurso voluntario<\/strong>, presentado por el propio empresario insolvente, en el plazo establecido.<\/li>\n<li><strong>Concurso necesario<\/strong>, solicitado por cualquiera de los acreedores una vez agotados de forma infructuosa los recursos para el cobro de sus deudas.<\/li>\n<\/ul>\n<p>Existen diferencias en c\u00f3mo se desarrollar\u00e1 el procedimiento, dependiendo de si el concurso es voluntario o necesario que veremos m\u00e1s adelante<\/p>\n<p>Sin importar cu\u00e1l sea el caso, el administrador concursal iniciar\u00e1 las diligencias necesarias para encontrar y comunicar a todos los posibles acreedores de dicho proceso concursal. Hay dos medios a trav\u00e9s de los cuales el acreedor se enterar\u00e1 del proceso judicial en el que se encuentra su deudor, siendo estos los siguientes:<\/p>\n<p>\u25cf\u00a0 \u00a0 \u00a0 A trav\u00e9s de una carta enviada por el administrador concursal, en la que se le solicita que comunique su cr\u00e9dito pendiente por cobrar y se especificar\u00e1 un tiempo m\u00e1ximo para presentarlo.<\/p>\n<p>\u25cf\u00a0 \u00a0 \u00a0 La otra forma es mediante el bolet\u00edn oficial del estado, donde se har\u00e1 p\u00fablica la insolvencia del deudor.<\/p>\n<p>Esto conlleva posteriormente a las distintas fases del concurso de acreedores, en las que se tomar\u00e1n decisiones cruciales que afectar\u00e1n tanto al deudor como a los acreedores y dem\u00e1s partes implicadas en este proceso.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_saber_si_una_empresa_esta_en_concurso_de_acreedores\"><\/span>\u00bfC\u00f3mo saber si una empresa est\u00e1 en concurso de acreedores?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Tan importante es saber qu\u00e9 es un concurso de acreedores como conocer si determinada sociedad est\u00e1 inmersa en esta situaci\u00f3n. Lo m\u00e1s conveniente es pregunt\u00e1rselo a <strong>administradores o representantes de la propia empresa<\/strong>. Sin embargo, es normal querer ir un paso por delante y buscar <strong>alternativas<\/strong> donde poder informarnos detalladamente acerca del estado de una empresa.<\/p>\n<ul>\n<li>Registro P\u00fablico Concursal<\/li>\n<\/ul>\n<p>Una vez sabemos qu\u00e9 es un concurso de acreedores, en el caso de querer, adem\u00e1s, conocer si una empresa est\u00e1 inmersa en esta situaci\u00f3n, la <strong>fuente m\u00e1s fiable y oficial<\/strong> es el <a href=\"https:\/\/www.publicidadconcursal.es\/\" target=\"_blank\" rel=\"noopener nofollow\">Registro P\u00fablico Concursal<\/a>. Dicho registro es de <strong>acceso p\u00fablico y gratuito<\/strong> y a trav\u00e9s de \u00e9l podremos obtener informaci\u00f3n acerca de las empresas en concurso de acreedores o que est\u00e9n en plena negociaci\u00f3n de sus deudas y obligaciones por alguno de los mecanismos de la Ley Concursal.<\/p>\n<ul>\n<li>Bolet\u00edn Oficial del Estado (BOE)<\/li>\n<\/ul>\n<p>Dado que en el BOE se publican los <strong>autos judiciales<\/strong> de declaraci\u00f3n de concurso, solo habr\u00e1 que acudir a la <strong>secci\u00f3n IV del Bolet\u00edn<\/strong> en lo referente a la Administraci\u00f3n de Justicia. All\u00ed encontraremos una breve <strong>nota del edicto que incluir\u00e1 los siguiente datos<\/strong>:<\/p>\n<ul>\n<li>Juzgado que decreta la declaraci\u00f3n de concurso de acreedores.<\/li>\n<li>Fecha y n\u00famero de autos del procedimiento concursal.<\/li>\n<li>NIF y domicilio del concursado.<\/li>\n<li>Designaci\u00f3n de administraci\u00f3n concursal y sus facultades<\/li>\n<li>Certificados de solvencia<\/li>\n<li>Estos certificados son emitidos por los cbanos, encargados de declarar si las sociedades mercantiles est\u00e1n al corriente de sus <strong>pagos y si tienen o no constancia de alguna incidencia en el Registro<\/strong>. De hecho, las entidades financieras est\u00e1n muy al tanto del BOE, ya que les interesa conocer cuanto antes la publicaci\u00f3n de los concursos de acreedores.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_pasa_si_la_empresa_entra_en_concurso_de_acreedores\"><\/span>\u00bfQu\u00e9 pasa si la empresa entra en concurso de acreedores?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Una vez sabemos qu\u00e9 es un concurso de acreedores, c\u00f3mo y cu\u00e1ndo se declara, debemos entender bien cu\u00e1les son sus consecuencias.<br \/>\nCuando el juez determina que la empresa ha entrado en este proceso, se procede a la <strong>suspensi\u00f3n de los pagos e intereses<\/strong> que la compa\u00f1\u00eda debe abonar hasta que finalice este proceso. Por tanto, <strong>esta etapa se extender\u00e1 mientras dure el concurso de acreedores<\/strong>.<\/p>\n<p>Tambi\u00e9n ser\u00e1 el juez quien designe a un <strong>equipo<\/strong>\u00a0<strong>de administradores concursales para que se hagan cargo de la gesti\u00f3n de la empresa a posteriori<\/strong>. Estos pueden ser:<\/p>\n<ul>\n<li>Un abogado concursal.<\/li>\n<li>Un economista, administrador o auditor en el \u00e1rea.<\/li>\n<li>Un representante por parte de los acreedores.<\/li>\n<li>Despu\u00e9s de haber iniciado el proceso de concurso, el <strong>juez puede tanto inhabilitar como restringir las funciones del empresario<\/strong>, si as\u00ed lo considera. Finalmente, los administradores concursales sustituir\u00e1n al empresario en su rol.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Como_empresa_%C2%BFme_pueden_embargar_estando_en_concurso_de_acreedores\"><\/span>Como empresa, \u00bfme pueden embargar estando en concurso de acreedores?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En general, las empresas que ya conocen el significado de un concurso de acreedores en las que se ven implicadas, cuando est\u00e1n dentro del propio proceso, <strong>se suspenden los embargos y ejecuciones judiciales contra la empresa<\/strong>, ya que se <strong>busca proteger los bienes y recursos de la compa\u00f1\u00eda<\/strong> <strong>para poder pagar a sus acreedores<\/strong> de manera equitativa. Sin embargo, puede haber algunas <strong>excepciones<\/strong>,\u00a0dependiendo de las circunstancias espec\u00edficas del caso. Aqu\u00ed os dejamos un par de ejemplos:<\/p>\n<ul>\n<li>Si existen embargos o ejecuciones judiciales previas al inicio del concurso y ya han sido dictados y notificados al deudor antes de abrir el concurso, estos podr\u00edan continuar en marcha.<\/li>\n<li>Si el embargo se produce despu\u00e9s de la declaraci\u00f3n del concurso, pero se trata de uno que no afecta a los bienes necesarios para la actividad empresarial y satisfacci\u00f3n de los acreedores, tambi\u00e9n podr\u00eda seguir en marcha.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Diferencias_entre_concurso_de_acreedores_particulares_y_concurso_de_acreedores_voluntario\"><\/span>Diferencias entre concurso de acreedores particulares y concurso de acreedores voluntario<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Una vez aclarado qu\u00e9 es un concurso de acreedores y c\u00f3mo se ejecuta, debemos conocer tambi\u00e9n la principal <strong>diferencia entre un concurso de acreedores voluntario y uno particular radica en qui\u00e9n inicia el proceso<\/strong>. En este sentido, dir\u00edamos que:<\/p>\n<ul>\n<li><strong>Concurso de acreedores voluntario<\/strong>: es la empresa la que toma la iniciativa de solicitar el concurso ante el juez,es decir, la empresa decide voluntariamente someterse a este proceso con el fin de reorganizar su situaci\u00f3n financiera.<\/li>\n<li><strong>Concurso de acreedores particulares<\/strong>: son los propios acreedores de la empresa quienes solicitan el concurso ante el juez, ya que considera que la empresa no est\u00e1 cumpliendo con sus obligaciones de pago.<\/li>\n<\/ul>\n<p>Sin importar cu\u00e1l sea el caso, el administrador concursal iniciar\u00e1 las diligencias necesarias para encontrar y comunicar a todos los posibles acreedores de dicho proceso concursal. <strong>Hay dos medios a trav\u00e9s de los cuales el acreedor se enterar\u00e1 del proceso judicial en el que se encuentra su deudor, siendo estos los siguientes<\/strong>:<\/p>\n<ul>\n<li>A trav\u00e9s de una carta enviada por el administrador concursal, en la que se le solicita que comunique su cr\u00e9dito pendiente por cobrar y se especificar\u00e1 un tiempo m\u00e1ximo para presentarlo.<\/li>\n<li>La otra forma es mediante el bolet\u00edn oficial del estado, donde se har\u00e1 p\u00fablica la insolvencia del deudor.<\/li>\n<\/ul>\n<p>Esto conlleva posteriormente a las distintas fases del concurso de acreedores, en las que se tomar\u00e1n decisiones cruciales que afectar\u00e1n tanto al deudor como a los acreedores y dem\u00e1s partes implicadas en este proceso.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Fases_del_concurso_de_acreedores\"><\/span>Fases del concurso de acreedores<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Quien conoce bien qu\u00e9 es un concurso de acreedores sabe que, normalmente, todo concurso de acreedores o procedimiento de insolvencia, ocupa <strong>varias etapas en su desarrollo<\/strong>:<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Actos_previos\"><\/span>Actos previos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Como indica su propio nombre, en esta fase se dar\u00e1n los <strong>primeros pasos del procedimiento<\/strong> solicitando iniciar el concurso y presentando la documentaci\u00f3n.<\/p>\n<p>Aqu\u00ed tambi\u00e9n tendremos en cuenta la <strong>deuda concursal<\/strong>, que es el conjunto de deudas que una empresa en concurso tiene con sus acreedores y que son objeto del proceso de concurso. Estas deudas se diferencian de otras que la empresa pueda tener ya que estas se encuentran incluidas en el proceso de concurso y est\u00e1n sujetas a las decisiones y resoluciones del juez y administraci\u00f3n concursal.<\/p>\n<p>Esta es una <strong>etapa tan amplia como compleja<\/strong> en la cual se barajan los presupuestos de la declaraci\u00f3n del concurso y los fundamentos del procedimiento para la declaraci\u00f3n del concurso.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Fase_comun\"><\/span>Fase com\u00fan<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Otro de los aspectos que interesan m\u00e1s conocer, adem\u00e1s de entender qu\u00e9 es un concurso de acreedores y qu\u00e9 implica, es saber en qu\u00e9 consiste la denominada \u2018Fase com\u00fan\u2019. Esta comienza cuando <strong>el juez revisa la documentaci\u00f3n presentada y declara, si procede, el concurso de acreedores<\/strong>. Una vez declarado el concurso mediante una resoluci\u00f3n judicial que se denomina Auto, se publicar\u00e1 en el BOE. La fecha de publicaci\u00f3n en el BOE, adem\u00e1s de la comunicaci\u00f3n que la administraci\u00f3n concursal realiza a los acreedores, inicia el plazo para la comunicaci\u00f3n de los cr\u00e9ditos existentes frente a la concursada.<\/p>\n<p>Una vez declarado:<\/p>\n<ul>\n<li>El <strong>deudor<\/strong>: debe colaborar en el procedimiento y se le restringe la capacidad de disponer libremente de su patrimonio.<\/li>\n<li>Los <strong>acreedores<\/strong>: su capacidad para reclamar se ver\u00e1 limitada y se suspender\u00e1n todas las ejecuciones pendientes, as\u00ed como la presentaci\u00f3n de nuevas demandas durante la duraci\u00f3n del concurso.<\/li>\n<li>Los<strong> administradores concursales<\/strong>: ser\u00e1n los encargados de gestionar los bienes del empresario y su activo, adem\u00e1s de tener que presentar un informe econ\u00f3mico en un plazo de menos de dos meses.<\/li>\n<\/ul>\n<p>El objetivo de esta fase es definir el alcance que tiene el concurso y preservar el patrimonio de la entidad deudora. En el Auto de declaraci\u00f3n del concurso se designa a la administraci\u00f3n concursal. Su principal objetivo es conservar la masa activa de la compa\u00f1\u00eda o persona f\u00edsica concursada y presentar\u00e1 en los primeros meses unos textos provisionales con la identificaci\u00f3n de sus acreedores, de sus correspondientes cr\u00e9ditos, y un inventario patrimonial de la concursada que incluye sus bienes y derechos, es decir, el activo de la concursada. Los acreedores podr\u00e1n impugnar estos textos provisionales, en su caso, si no est\u00e1n de acuerdo con la calificaci\u00f3n o la cuant\u00eda de sus cr\u00e9ditos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Fase_de_resolucion\"><\/span>Fase de resoluci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>En el proceso completo de informarse sobre qu\u00e9 es un concurso de acreedores, hay que tener, adem\u00e1s de las dos anteriores fases, una tercera realmente importante. En esta, habr\u00e1 dos posibles resoluciones:<\/p>\n<ul>\n<li><strong>Liquidaci\u00f3n concursal<\/strong>: no se puede llegar a un acuerdo de pago con los acreedores, por lo que se tendr\u00e1 que liquidar su patrimonio para abonar los cr\u00e9ditos existentes.<\/li>\n<li><strong style=\"font-size: inherit;\">Fase de Convenio<\/strong><span style=\"font-size: inherit;\">: es posible llegar a un acuerdo con los acreedores en el que la deuda se satisface mediante esperas o quita de deuda.<\/span><\/li>\n<\/ul>\n<p>La siguiente fase ir\u00e1 en relaci\u00f3n con esta \u00faltima resoluci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Calificacion_del_concurso\"><\/span>Calificaci\u00f3n del concurso<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Si se decide ejecutar la liquidaci\u00f3n del patrimonio del deudor, habr\u00e1 tambi\u00e9n que calificar el concurso como culpable o fortuito<\/strong>, dependiendo de cada caso en particular. Si el deudor es encontrado culpable, se producir\u00e1n una serie de consecuencias:<\/p>\n<ul>\n<li>P\u00e9rdida de los derechos de cobro.<\/li>\n<li>Exigencia de responsabilidad civil o penal.<\/li>\n<li>Inhabilitaci\u00f3n para representar o administrar bienes o personas.<\/li>\n<li>Obligaci\u00f3n de restituir los bienes obtenidos de manera indebida.<\/li>\n<\/ul>\n<p>En algunos casos, se podr\u00eda <strong>reabrir el concurso<\/strong> si aparecen nuevos bienes en un plazo de cinco a\u00f1os que puedan satisfacer las deudas pendientes. Sin embargo, tambi\u00e9n es importante saber el <strong>tiempo que una empresa puede estar en un concurso de acreedores<\/strong>. Resolveremos esta duda a continuaci\u00f3n.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuanto_tiempo_se_tarda_en_resolver_un_concurso_de_acreedores\"><\/span>\u00bfCu\u00e1nto tiempo se tarda en resolver un concurso de acreedores?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Quienes ya saben qu\u00e9 es un concurso de acreedores saben que, por lo general, el <strong>proceso de concurso de acreedores suele durar al menos un a\u00f1o<\/strong> desde los actos previos hasta la fase de calificaci\u00f3n.<\/p>\n<p>La <strong>duraci\u00f3n del proceso puede variar dependiendo de quien presente la solicitud de concurso<\/strong> y de la propia complejidad del caso. En general, el concurso de acreedores voluntario, presentado por el propio deudor, suele tener una duraci\u00f3n menor que el concurso de particulares. Por tanto, el tiempo de duraci\u00f3n de este procedimiento legal puede verse afectado por este factor.<\/p>\n<p>Aqu\u00ed, nos gustar\u00eda hacer menci\u00f3n tambi\u00e9n al <strong>concurso de acreedores expr\u00e9s<\/strong>. Bajo la denominaci\u00f3n de concurso expr\u00e9s se conoce al procedimiento de concurso de acreedores que concluye de forma simult\u00e1nea a su declaraci\u00f3n.<\/p>\n<p>Se trata del supuesto en que, desde la propia solicitud de concurso de acreedores, el juez o jueza de lo mercantil competente puede determinar que la masa activa es insuficiente para hacer frente tan siquiera a los costes propios del procedimiento concursal.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podemos definir el concurso de acreedores como un procedimiento judicial a disposici\u00f3n de toda empresa o persona f\u00edsica que pasa por una situaci\u00f3n de insolvencia econ\u00f3mica derivada de la imposibilidad de atender los pagos a sus acreedores. El objetivo de este procedimiento, es buscar una soluci\u00f3n a los problemas de falta de liquidez y solvencia &#8230; <a title=\"\u00bfQu\u00e9 es un concurso de acreedores?\" class=\"read-more\" href=\"https:\/\/www.paypymes.es\/blog\/que-es-un-concurso-de-acreedores\/\" aria-label=\"M\u00e1s en \u00bfQu\u00e9 es un concurso de acreedores?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":104,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impagos"],"_links":{"self":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/comments?post=103"}],"version-history":[{"count":3,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts\/103\/revisions"}],"predecessor-version":[{"id":107,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/posts\/103\/revisions\/107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/media\/104"}],"wp:attachment":[{"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/media?parent=103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/categories?post=103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paypymes.es\/blog\/wp-json\/wp\/v2\/tags?post=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}